{"id":4764,"date":"2017-10-02T16:36:41","date_gmt":"2017-10-02T19:36:41","guid":{"rendered":"http:\/\/comunidadtextil.com\/wpnews\/?p=4764"},"modified":"2017-10-02T17:30:45","modified_gmt":"2017-10-02T20:30:45","slug":"la-industria-de-la-moda-es-optimista-respecto-de-los-resultados-de-2017-y-2018","status":"publish","type":"post","link":"https:\/\/comunidadtextil.com\/wpnews\/2017\/10\/la-industria-de-la-moda-es-optimista-respecto-de-los-resultados-de-2017-y-2018\/","title":{"rendered":"La industria de la moda es optimista respecto de los resultados de 2017 y 2018"},"content":{"rendered":"<p><a href=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2017\/10\/descarga.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-4756\" src=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2017\/10\/descarga.jpg\" alt=\"\" width=\"275\" height=\"183\" srcset=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2017\/10\/descarga.jpg 275w, https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2017\/10\/descarga-150x100.jpg 150w\" sizes=\"auto, (max-width: 275px) 100vw, 275px\" \/><\/a>La consultora global McKinsey inform\u00f3 que el 40% de los ejecutivos que trabajan en empresas internacionales de moda esperan que las condiciones del sector mejoren considerablemente en lo que queda del a\u00f1o. Cuando fueron consultados en la misma \u00e9poca del a\u00f1o pasado, solo el 19% mostr\u00f3 optimismo.<\/p>\n<p>De hecho, las principales empresas del sector vienen de implementar estrategias de reestructuraci\u00f3n y disminuci\u00f3n de costos, por lo cual calculan que los beneficios de estas pol\u00edticas pronto dar\u00e1n sus frutos.<\/p>\n<div id=\"attachment_4755\" style=\"width: 210px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2017\/10\/Gabriel-Far\u00edas-Iribarren-especialista-en-aprovisionamiento-textil-_1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4755\" class=\"size-full wp-image-4755\" src=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2017\/10\/Gabriel-Far\u00edas-Iribarren-especialista-en-aprovisionamiento-textil-_1.jpg\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2017\/10\/Gabriel-Far\u00edas-Iribarren-especialista-en-aprovisionamiento-textil-_1.jpg 200w, https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2017\/10\/Gabriel-Far\u00edas-Iribarren-especialista-en-aprovisionamiento-textil-_1-150x150.jpg 150w, https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2017\/10\/Gabriel-Far\u00edas-Iribarren-especialista-en-aprovisionamiento-textil-_1-80x80.jpg 80w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><p id=\"caption-attachment-4755\" class=\"wp-caption-text\">Gabriel Far\u00edas Iribarren, especialista en aprovisionamiento textil<\/p><\/div>\n<p>Gabriel Far\u00edas Iribarren, especialista en aprovisionamiento textil, afirm\u00f3 que para que las empresas aprovechen esta mejora deben tener en cuenta ciertas tendencias actuales de la industria de la moda.<\/p>\n<p>Para Far\u00edas Iribarren, hay que tener en cuenta que el cambio constante ser\u00e1 una l\u00f3gica en todos los mercados y, por lo tanto, los ejecutivos y empresas deben aprender a moverse a este ritmo. Otro tema importante es la compra digital de productos, que hace que los vendedores minoristas deban reconsiderar las estrategias de compra que hasta hace poco funcionaban bien.<\/p>\n<p>Otro tema importante es la digitalizaci\u00f3n de la cadena de suministro de la industria de la moda, que bien aprovechada promueve la eficiencia y velocidad de los procesos y ayuda a disminuir los costos.<\/p>\n<p>Far\u00edas Iribarren tambi\u00e9n destac\u00f3 el tema de la responsabilidad social empresaria en el sector de la moda, ya que los consumidores de hoy en d\u00eda exigen que las marcas implementen medidas para proteger el medio ambiente y garantizar el bienestar social.<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<br \/>\nTextiles Panamericanos \/ Comunidad Textil<\/p>\n<p dir=\"ltr\">\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014<\/p>\n<p dir=\"ltr\">Para comunicarse con ComunidadTextil: <span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"mailto:contacto@comunidadtextil.com\">contacto@comunidadtextil.com<\/a><\/span><\/p>\n<table border=\"0\" width=\"460\">\n<tbody>\n<tr>\n<td width=\"300\"><a href=\"http:\/\/bit.ly\/2qWIP7i\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"\/publicidad\/banner-ciai.gif\" alt=\"\" width=\"300\" height=\"153\" border=\"0\" \/><\/a><\/td>\n<td width=\"171\"><a href=\"http:\/\/bit.ly\/2qrhruB\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"\/ciunky300x200.jpg\" width=\"290\" height=\"auto\" border=\"0\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>La consultora global McKinsey inform\u00f3 que el 40% de los ejecutivos que trabajan en empresas internacionales de moda esperan que las condiciones del sector mejoren considerablemente en lo que queda del a\u00f1o. Cuando fueron consultados en la misma \u00e9poca del a\u00f1o pasado, solo el 19% mostr\u00f3 optimismo. De hecho, las principales empresas del sector vienen [&hellip;]<\/p>\n","protected":false},"author":1924,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,57],"tags":[],"class_list":["post-4764","post","type-post","status-publish","format-standard","hentry","category-industria-de-la-confeccion","category-mercados","count-0","even alt","author-adminct","last"],"_links":{"self":[{"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/posts\/4764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/users\/1924"}],"replies":[{"embeddable":true,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/comments?post=4764"}],"version-history":[{"count":3,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/posts\/4764\/revisions"}],"predecessor-version":[{"id":4774,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/posts\/4764\/revisions\/4774"}],"wp:attachment":[{"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/media?parent=4764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/categories?post=4764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/tags?post=4764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}