{"id":19782,"date":"2026-01-29T11:24:39","date_gmt":"2026-01-29T14:24:39","guid":{"rendered":"http:\/\/comunidadtextil.com\/wpnews\/?p=19782"},"modified":"2026-01-29T14:19:25","modified_gmt":"2026-01-29T17:19:25","slug":"una-firma-china-compro-el-29-de-la-marca-deportiva-puma-por-us-1-800-m","status":"publish","type":"post","link":"https:\/\/comunidadtextil.com\/wpnews\/2026\/01\/una-firma-china-compro-el-29-de-la-marca-deportiva-puma-por-us-1-800-m\/","title":{"rendered":"Una firma china compr\u00f3 el 29% de la marca deportiva Puma por US$ 1.800 M"},"content":{"rendered":"<p>Anta Sports, la mayor marca china de ropa deportiva, se ha convertido en el mayor accionista de la empresa alemana fundada por Rudolf Dassler. Esta operaci\u00f3n permitir\u00e1 que la compa\u00f1\u00eda aumente sus ventas en el mercado chino cuyo potencial quiere ser aprovechado por los nuevos socios.<\/p>\n<table>\n<tbody>\n<tr>\n<td><a href=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma-_4-1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-19771 aligncenter\" src=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma-_4-1-1-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma-_4-1-1-200x300.jpg 200w, https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma-_4-1-1-683x1024.jpg 683w, https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma-_4-1-1.jpg 768w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/td>\n<td><a href=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/indumentaria_puma-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-19770 aligncenter\" src=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/indumentaria_puma-1-207x300.jpg\" alt=\"\" width=\"207\" height=\"300\" srcset=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/indumentaria_puma-1-207x300.jpg 207w, https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/indumentaria_puma-1.jpg 333w\" sizes=\"auto, (max-width: 207px) 100vw, 207px\" \/><\/a><\/td>\n<td><a href=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma3-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19774 size-medium aligncenter\" src=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma3-1-e1769696541721-218x300.png\" alt=\"\" width=\"218\" height=\"300\" srcset=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma3-1-e1769696541721-218x300.png 218w, https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma3-1-e1769696541721.png 727w\" sizes=\"auto, (max-width: 218px) 100vw, 218px\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Anta Sports anunci\u00f3 que le compr\u00f3 la participaci\u00f3n accionaria del 29,06% de Puma a la familia Pinault (propietarios de Kering, que controla a Artemis y era titular de la marca) por US$ 1.800 millones. La marca de origen alem\u00e1n cotiza en la bolsa de Hong Kong con un valor de US$ 27.800 millones.<\/p>\n<p>Al conocerse la noticia, las acciones de Kering (controlada por Artemis) subieron 1% en la bolsa de Par\u00eds mientras que las de Puma lo hicieron en un 3%.<\/p>\n<p>Wei Lin, vicepresidente global de Anta de Costenibilidad y Relaciones con los Inversores, sostuvo con respecto a la compra del paquete accionario que \u201cPuma tiene m\u00e1s potencial en el mercado chino, donde est\u00e1n infrarrepresentados con solo el 7% de sus ingresos globales. Tenemos muchas ideas sobre c\u00f3mo hacer que Puma tenga m\u00e1s \u00e9xito en China\u201d.<\/p>\n<p><a href=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma-__baja-1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-19772 alignright\" src=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma-__baja-1-1-300x191.jpg\" alt=\"\" width=\"247\" height=\"157\" srcset=\"https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma-__baja-1-1-300x191.jpg 300w, https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma-__baja-1-1-768x490.jpg 768w, https:\/\/comunidadtextil.com\/wpnews\/wp-content\/uploads\/2026\/01\/Puma-__baja-1-1.jpg 1000w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><\/a>Anta anticip\u00f3 que, una vez finalizada la operaci\u00f3n, pedir\u00e1 puestos en el Consejo de Administraci\u00f3n pero que no tiene planeado adquirir el total de la empresa. La transacci\u00f3n se realiz\u00f3 con fondos propios de la firma china que decidi\u00f3 comprar las acciones de Puma \u201cpara avanzar en su estrategia de internacionalizaci\u00f3n y diversificaci\u00f3n de marcas en el sector deportivo\u201d.<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<br \/>\nMarket Screener \/ Infobae \/ Comunidad Textil<\/p>\n<p>\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014<\/p>\n<p dir=\"ltr\">Para comunicarse con ComunidadTextil: <span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"mailto:contacto@comunidadtextil.com\">contacto@comunidadtextil.com<\/a><\/span><\/p>\n<table border=\"0\" width=\"460\">\n<tbody>\n<tr>\n<td width=\"auto\"><a href=\"https:\/\/www.aplf.com\/aplf-2026\/fashion-access-fair-details\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/comunidadtextil.com\/publicidad\/2025\/aplf26_fasacc_banner_300x300.png\" width=\"300\" height=\"300\" \/><\/a><\/td>\n<td width=\"auto\"><a href=\"https:\/\/www.instagram.com\/institutobelkynuic\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/comunidadtextil.com\/cursos300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" border=\"0\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Anta Sports, la mayor marca china de ropa deportiva, se ha convertido en el mayor accionista de la empresa alemana fundada por Rudolf Dassler. Esta operaci\u00f3n permitir\u00e1 que la compa\u00f1\u00eda aumente sus ventas en el mercado chino cuyo potencial quiere ser aprovechado por los nuevos socios. Anta Sports anunci\u00f3 que le compr\u00f3 la participaci\u00f3n accionaria [&hellip;]<\/p>\n","protected":false},"author":1924,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-19782","post","type-post","status-publish","format-standard","hentry","category-empresas-negocios","count-0","even alt","author-adminct","last"],"_links":{"self":[{"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/posts\/19782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/users\/1924"}],"replies":[{"embeddable":true,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/comments?post=19782"}],"version-history":[{"count":6,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/posts\/19782\/revisions"}],"predecessor-version":[{"id":19793,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/posts\/19782\/revisions\/19793"}],"wp:attachment":[{"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/media?parent=19782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/categories?post=19782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunidadtextil.com\/wpnews\/wp-json\/wp\/v2\/tags?post=19782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}